{"id":6316,"date":"2022-11-29T09:16:29","date_gmt":"2022-11-29T06:16:29","guid":{"rendered":"https:\/\/www.prolepsis.gr\/?page_id=6316"},"modified":"2022-11-29T09:17:31","modified_gmt":"2022-11-29T06:17:31","slug":"content","status":"publish","type":"page","link":"https:\/\/www.prolepsis.gr\/gr\/content\/","title":{"rendered":"Content"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6316","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Content - Prolepsis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.prolepsis.gr\/gr\/content\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Content - Prolepsis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.prolepsis.gr\/gr\/content\/\" \/>\n<meta property=\"og:site_name\" content=\"Prolepsis\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T06:17:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/content\/\",\"url\":\"https:\/\/www.prolepsis.gr\/gr\/content\/\",\"name\":\"Content - Prolepsis\",\"isPartOf\":{\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/#website\"},\"datePublished\":\"2022-11-29T06:16:29+00:00\",\"dateModified\":\"2022-11-29T06:17:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/content\/#breadcrumb\"},\"inLanguage\":\"gr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.prolepsis.gr\/gr\/content\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/content\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.prolepsis.gr\/gr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Content\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/#website\",\"url\":\"https:\/\/www.prolepsis.gr\/gr\/\",\"name\":\"Prolepsis\",\"description\":\"Prolepsis\",\"publisher\":{\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.prolepsis.gr\/gr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gr\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/#organization\",\"name\":\"Prolepsis\",\"url\":\"https:\/\/www.prolepsis.gr\/gr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gr\",\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.prolepsis.gr\/wp-content\/uploads\/2022\/11\/logo-30-xronia-prolepsis-gr.png\",\"contentUrl\":\"https:\/\/www.prolepsis.gr\/wp-content\/uploads\/2022\/11\/logo-30-xronia-prolepsis-gr.png\",\"width\":342,\"height\":76,\"caption\":\"Prolepsis\"},\"image\":{\"@id\":\"https:\/\/www.prolepsis.gr\/gr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Content - Prolepsis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.prolepsis.gr\/gr\/content\/","og_locale":"en_US","og_type":"article","og_title":"Content - Prolepsis","og_url":"https:\/\/www.prolepsis.gr\/gr\/content\/","og_site_name":"Prolepsis","article_modified_time":"2022-11-29T06:17:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.prolepsis.gr\/gr\/content\/","url":"https:\/\/www.prolepsis.gr\/gr\/content\/","name":"Content - Prolepsis","isPartOf":{"@id":"https:\/\/www.prolepsis.gr\/gr\/#website"},"datePublished":"2022-11-29T06:16:29+00:00","dateModified":"2022-11-29T06:17:31+00:00","breadcrumb":{"@id":"https:\/\/www.prolepsis.gr\/gr\/content\/#breadcrumb"},"inLanguage":"gr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.prolepsis.gr\/gr\/content\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.prolepsis.gr\/gr\/content\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.prolepsis.gr\/gr\/"},{"@type":"ListItem","position":2,"name":"Content"}]},{"@type":"WebSite","@id":"https:\/\/www.prolepsis.gr\/gr\/#website","url":"https:\/\/www.prolepsis.gr\/gr\/","name":"Prolepsis","description":"Prolepsis","publisher":{"@id":"https:\/\/www.prolepsis.gr\/gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.prolepsis.gr\/gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gr"},{"@type":"Organization","@id":"https:\/\/www.prolepsis.gr\/gr\/#organization","name":"Prolepsis","url":"https:\/\/www.prolepsis.gr\/gr\/","logo":{"@type":"ImageObject","inLanguage":"gr","@id":"https:\/\/www.prolepsis.gr\/gr\/#\/schema\/logo\/image\/","url":"https:\/\/www.prolepsis.gr\/wp-content\/uploads\/2022\/11\/logo-30-xronia-prolepsis-gr.png","contentUrl":"https:\/\/www.prolepsis.gr\/wp-content\/uploads\/2022\/11\/logo-30-xronia-prolepsis-gr.png","width":342,"height":76,"caption":"Prolepsis"},"image":{"@id":"https:\/\/www.prolepsis.gr\/gr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/pages\/6316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/comments?post=6316"}],"version-history":[{"count":1,"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/pages\/6316\/revisions"}],"predecessor-version":[{"id":6317,"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/pages\/6316\/revisions\/6317"}],"wp:attachment":[{"href":"https:\/\/www.prolepsis.gr\/gr\/wp-json\/wp\/v2\/media?parent=6316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}